{"id":10820,"date":"2020-10-27T11:10:37","date_gmt":"2020-10-27T11:10:37","guid":{"rendered":"https:\/\/revista-apunts.com\/?p=10820"},"modified":"2020-12-12T12:54:43","modified_gmt":"2020-12-12T12:54:43","slug":"una-obra-de-josep-fossas-per-a-linefc","status":"publish","type":"post","link":"https:\/\/revista-apunts.com\/ca\/una-obra-de-josep-fossas-per-a-linefc\/","title":{"rendered":"Una obra de Josep Fossas per a L&#8217;INEFC"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Resum<\/h2>\n\n\n<div align=\"\">\n<p class=\"journal-abstract\">A les primeries d&#8217;enguany, Josep Fossas (Capdev\u00e0nol, 1940) va presentar en el Museu de l&#8217;Esport de Barcelona,la s\u00e8rie pict\u00f2rica Interpreta-cions d&#8217;esports ol\u00edmpics. La interessant col&#8217;lecci\u00f3 va \u00e9sser adquirida pel Comit\u00e8 Internacional Ol\u00edmpic, el qual va cedir despr\u00e9s, en dip\u00f2sit, algunes de les obres a diferents entitats esportives. Una de les institucions afavorides ha estat l&#8217;Institut Nacional d&#8217;Educaci\u00f3 F\u00edsica de Catalunya, al qualli ha estat assignat el d\u00edptic, H\u00edpica. Interpretacions d&#8217;esports ol\u00edmpics \u00e9s un conjunt de quinze pintures, dedicades a diferents especialitats ol\u00edmpiques (atletisme, b\u00e0squet, ciclisme, curses sobre gel, esqu\u00ed, futbol, gimn\u00e0stica, h\u00edpica, hoquei, nataci\u00f3, pirag\u00fcisme, salt d&#8217;esqu\u00ed, tennis, vela i waterpolo). Tretze de les obres estan realitzades en forma de d\u00edptic \u2014horitzontal o vertical\u2014 la qual cosa permet aconseguir una major amplitud de l&#8217;acci\u00f3 representada.<\/p>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Resum A les primeries d&#8217;enguany, Josep Fossas (Capdev\u00e0nol, 1940) va presentar en el Museu de l&#8217;Esport de Barcelona,la s\u00e8rie pict\u00f2rica Interpreta-cions d&#8217;esports ol\u00edmpics. La interessant col&#8217;lecci\u00f3 va \u00e9sser adquirida pel Comit\u00e8 Internacional Ol\u00edmpic, el qual va cedir despr\u00e9s, en dip\u00f2sit, algunes de les obres a diferents entitats esportives. Una de les institucions afavorides ha estat [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[44,8518],"tags":[],"author_meta":{"display_name":"doc_inefc","author_link":"https:\/\/revista-apunts.com\/ca\/author\/doc_inefc\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/revista-apunts.com\/ca\/category\/ciencies-humanes-i-socials-ca\/\" class=\"advgb-post-tax-term\">Ci\u00e8ncies humanes i socials<\/a>","<a href=\"https:\/\/revista-apunts.com\/ca\/category\/opinio\/\" class=\"advgb-post-tax-term\">Opini\u00f3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Ci\u00e8ncies humanes i socials<\/span>","<span class=\"advgb-post-tax-term\">Opini\u00f3<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 6 anys ago","modified":"Updated 5 anys ago"},"absolute_dates":{"created":"Posted on 27 octubre 2020","modified":"Updated on 12 desembre 2020"},"absolute_dates_time":{"created":"Posted on 27 octubre 2020 11:10","modified":"Updated on 12 desembre 2020 12:54"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10820\/"}],"collection":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/comments\/?post=10820"}],"version-history":[{"count":1,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10820\/revisions\/"}],"predecessor-version":[{"id":34040,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10820\/revisions\/34040\/"}],"wp:attachment":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/media\/?parent=10820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/categories\/?post=10820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/tags\/?post=10820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}