{"id":10750,"date":"2020-10-27T11:10:04","date_gmt":"2020-10-27T11:10:04","guid":{"rendered":"https:\/\/revista-apunts.com\/?p=10750"},"modified":"2021-01-21T12:59:11","modified_gmt":"2021-01-21T12:59:11","slug":"lesport-per-atendre-la-diversitat-esport-adaptat-i-esport-inclusiu","status":"publish","type":"post","link":"https:\/\/revista-apunts.com\/ca\/lesport-per-atendre-la-diversitat-esport-adaptat-i-esport-inclusiu\/","title":{"rendered":"L&#8217;esport per atendre la diversitat: esport adaptat i esport inclusiu"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Resum<\/h2>\n\n\n<div align=\"\">\n<p class=\"journal-abstract\">Introducci\u00f3 a l&#8217;esport adaptat (breu ressenya hist\u00f2rica, concepte, funcions, context &#8230;). L&#8217;esport per atendre la diversitat com a concepte que acull l&#8217;esport adaptat i l&#8217;esport inclusiu. L&#8217;esport per atendre la diversitat com la manifestaci\u00f3 esportiva que at\u00e9n a les persones que no estan incloses en l&#8217;\u00e0mbit social. Aquestes persones estan associades a factors f\u00edsics, ps\u00edquics, rendiment esportiu, socioecon\u00f2mics, \u00e8tnico-culturals, etc. Per \u00faltim, una classificaci\u00f3 orientativa sobre les diferents persones que fan esport, d&#8217;acord amb els factors associats que presenten, i fan que l&#8217;esport satisfaci a grups de poblaci\u00f3 heterog\u00e8nia, amb necessitats especials, en les seves dues perspectives principals que s\u00f3n l&#8217;esport adaptat i l&#8217;esport inclusiu.<\/p>\n<div class=\"journal-keywords\">\u00a0<\/div>\n<br \/>\n<p>\u00a0<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Resum Introducci\u00f3 a l&#8217;esport adaptat (breu ressenya hist\u00f2rica, concepte, funcions, context &#8230;). L&#8217;esport per atendre la diversitat com a concepte que acull l&#8217;esport adaptat i l&#8217;esport inclusiu. L&#8217;esport per atendre la diversitat com la manifestaci\u00f3 esportiva que at\u00e9n a les persones que no estan incloses en l&#8217;\u00e0mbit social. Aquestes persones estan associades a factors f\u00edsics, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[8509],"tags":[],"author_meta":{"display_name":"doc_inefc","author_link":"https:\/\/revista-apunts.com\/ca\/author\/doc_inefc\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/revista-apunts.com\/ca\/category\/apunts-per-al-segle-xxi\/\" class=\"advgb-post-tax-term\">Apunts per al segle XXI<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Apunts per al segle XXI<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 6 anys ago","modified":"Updated 5 anys ago"},"absolute_dates":{"created":"Posted on 27 octubre 2020","modified":"Updated on 21 gener 2021"},"absolute_dates_time":{"created":"Posted on 27 octubre 2020 11:10","modified":"Updated on 21 gener 2021 12:59"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10750\/"}],"collection":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/comments\/?post=10750"}],"version-history":[{"count":1,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10750\/revisions\/"}],"predecessor-version":[{"id":43736,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10750\/revisions\/43736\/"}],"wp:attachment":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/media\/?parent=10750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/categories\/?post=10750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/tags\/?post=10750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}