{"id":10444,"date":"2020-10-27T11:07:15","date_gmt":"2020-10-27T11:07:15","guid":{"rendered":"https:\/\/revista-apunts.com\/?p=10444"},"modified":"2020-11-26T12:19:12","modified_gmt":"2020-11-26T12:19:12","slug":"tiretes-nasals-i-entrenamentde-la-forca-resistencia-en-triatlo","status":"publish","type":"post","link":"https:\/\/revista-apunts.com\/ca\/tiretes-nasals-i-entrenamentde-la-forca-resistencia-en-triatlo\/","title":{"rendered":"Tiretes nasals i entrenament\nde la for\u00e7a-resist\u00e8ncia en triatl\u00f3"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Resum<\/h2>\n\n\n<p>En la pr\u00e0ctica esportiva s\u2019ha est\u00e8s l\u2019\u00fas de tiretes col\u00b7locades al nas amb el prop\u00f2sit de millorar la respiraci\u00f3 nasal durant l\u2019esfor\u00e7. Per valorar-ne l\u2019efic\u00e0cia en un treball de for\u00e7a-resist\u00e8ncia que simula l\u2019estil bra\u00e7a de nataci\u00f3 sobre un banc isocin\u00e8tic, s\u2019han comparat en set triatletes els valors de consum d\u2019oxigen, la freq\u00fc\u00e8ncia card\u00edaca i la ventilaci\u00f3 en realitzar-ho amb una tireta nasal i sense. <br> Nom\u00e9s les escasses disminucions del consum d\u2019oxigen (entre 1,58 i 2,53 ml\/ kg\u00b7min), fent servir la tireta, van presentar difer\u00e8ncies (<em>p <\/em>&lt; 0,05) favorables a la seva utilitzaci\u00f3. Per contra, els valors de freq\u00fc\u00e8ncia card\u00edaca van suposar augments mitjans no significatius (<em>p<\/em> &gt; 0,05) compresos entre \u20131,36 i 6,7 pul\/min i la ventilaci\u00f3 va disminuir entre 2,42 i 16,05 l\/min (<em>p <\/em>&lt; 0,05). <br> L\u2019\u00fas de la tireta nasal va suposar una disminuci\u00f3 de la despesa energ\u00e8tica durant la realitzaci\u00f3 d\u2019un treball de for\u00e7a-resist\u00e8ncia en sec, on la respiraci\u00f3 era exclusivament nasal. Tanmateix, en la pr\u00e0ctica esportiva i, especialment en el medi aqu\u00e0tic, els triatletes i nedadors recorren a la respiraci\u00f3 oral o oronasal, especialment durant l\u2019espiraci\u00f3 en la fase aqu\u00e0tica, per la qual cosa els beneficis de l\u2019\u00fas de la tireta nasal podrien quedar minimitzats o fins i tot desapar\u00e8ixer.<\/p>\n\n <div class=\"tags\"> <p><strong>Paraules clau:<\/strong> <span>consum d'oxigen<\/span>, <span>For\u00e7a-resist\u00e8ncia<\/span>, <span>frequ\u0308\u00e8ncia card\u00edaca<\/span>, <span>tireta nasal<\/span>, <span>ventilaci\u00f3<\/span><\/p> <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Resum En la pr\u00e0ctica esportiva s\u2019ha est\u00e8s l\u2019\u00fas de tiretes col\u00b7locades al nas amb el prop\u00f2sit de millorar la respiraci\u00f3 nasal durant l\u2019esfor\u00e7. Per valorar-ne l\u2019efic\u00e0cia en un treball de for\u00e7a-resist\u00e8ncia que simula l\u2019estil bra\u00e7a de nataci\u00f3 sobre un banc isocin\u00e8tic, s\u2019han comparat en set triatletes els valors de consum d\u2019oxigen, la freq\u00fc\u00e8ncia card\u00edaca i [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[52],"tags":[4243,4248,532,4247,4249],"author_meta":{"display_name":"doc_inefc","author_link":"https:\/\/revista-apunts.com\/ca\/author\/doc_inefc\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">Preparaci\u00f3 f\u00edsica<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Preparaci\u00f3 f\u00edsica<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">consum d&#039;oxigen<\/a>","<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">For\u00e7a-resist\u00e8ncia<\/a>","<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">frequ\u0308\u00e8ncia card\u00edaca<\/a>","<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">tireta nasal<\/a>","<a href=\"https:\/\/revista-apunts.com\/ca\/category\/preparacio-fisica-ca\/\" class=\"advgb-post-tax-term\">ventilaci\u00f3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">consum d&#039;oxigen<\/span>","<span class=\"advgb-post-tax-term\">For\u00e7a-resist\u00e8ncia<\/span>","<span class=\"advgb-post-tax-term\">frequ\u0308\u00e8ncia card\u00edaca<\/span>","<span class=\"advgb-post-tax-term\">tireta nasal<\/span>","<span class=\"advgb-post-tax-term\">ventilaci\u00f3<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 6 anys ago","modified":"Updated 5 anys ago"},"absolute_dates":{"created":"Posted on 27 octubre 2020","modified":"Updated on 26 novembre 2020"},"absolute_dates_time":{"created":"Posted on 27 octubre 2020 11:07","modified":"Updated on 26 novembre 2020 12:19"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10444\/"}],"collection":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/comments\/?post=10444"}],"version-history":[{"count":1,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10444\/revisions\/"}],"predecessor-version":[{"id":32415,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/posts\/10444\/revisions\/32415\/"}],"wp:attachment":[{"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/media\/?parent=10444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/categories\/?post=10444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revista-apunts.com\/ca\/wp-json\/wp\/v2\/tags\/?post=10444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}